{"id":3560,"date":"2023-10-31T13:26:00","date_gmt":"2023-10-31T13:26:00","guid":{"rendered":"https:\/\/digitalearthafrica.org\/?p=3560"},"modified":"2025-05-29T12:50:18","modified_gmt":"2025-05-29T12:50:18","slug":"timely-monitoring-of-mangroves-in-somalia","status":"publish","type":"post","link":"https:\/\/digitalearthafrica.org\/fr\/timely-monitoring-of-mangroves-in-somalia\/","title":{"rendered":"Surveillance opportune des mangroves en Somalie"},"content":{"rendered":"<p>Les mangroves en Somalie jouent un r\u00f4le essentiel dans la r\u00e9duction de l'\u00e9rosion du littoral, et les habitats pour les poissons et les oiseaux sont essentiels \u00e0 la conservation de la diversit\u00e9 biologique. La Somalie poss\u00e8de le plus long littoral des pays d'Afrique continentale, environ 3500 km, avec des for\u00eats de mangroves trouv\u00e9es dans certaines zones le long de la c\u00f4te, sur les c\u00f4tes nord et sud-ouest, y compris dans la partie sud des \u00eeles Sa\u2019ad ad-Din et dans la zone c\u00f4ti\u00e8re proche de Djibouti. La Somalie a une couverture foresti\u00e8re mangrove totale de 48 kilom\u00e8tres carr\u00e9s, et l'\u00e9tendue des mangroves a diminu\u00e9 de 1,65 kilom\u00e8tre carr\u00e9 entre 1996 et 2020.<\/p>\n\n\n\n<p>La perte de biodiversit\u00e9, la d\u00e9gradation des habitats et la modification des \u00e9cosyst\u00e8mes de mangroves et de r\u00e9cifs coralliens le long du littoral font partie des principales pr\u00e9occupations environnementales dans la r\u00e9gion de la Corne de l'Afrique, en particulier en Somalie. Depuis 1991, la Somalie a subi une extr\u00eame d\u00e9gradation environnementale, naturelle et artificielle. La perte de biodiversit\u00e9 et la d\u00e9gradation des habitats de mangroves en Somalie sont des cons\u00e9quences \u00e9cologiques apparentes et visibles. Celles-ci r\u00e9sultent du changement climatique, qui provoque l'\u00e9l\u00e9vation du niveau de la mer et des temp\u00e9ratures \u00e9lev\u00e9es de l'eau entra\u00eenant le blanchiment des coraux, combin\u00e9es aux pressions humaines directes sur l'environnement c\u00f4tier et marin dues \u00e0 l'augmentation des populations c\u00f4ti\u00e8res, \u00e0 la pollution et \u00e0 une mauvaise gestion humaine.<\/p>\n\n\n\n<p>Malheureusement, ces habitats de mangrove r\u00e9gressent \u00e0 un rythme alarmant en raison du changement climatique. L'\u00e9rosion c\u00f4ti\u00e8re, l'\u00e9l\u00e9vation du niveau de la mer et les activit\u00e9s humaines ont contribu\u00e9 \u00e0 la d\u00e9gradation des mangroves et ont entra\u00een\u00e9 la perte de poissons adapt\u00e9s le long du rivage. L'objectif de d\u00e9veloppement durable (ODD) 14.5 des Nations Unies s'efforce de pr\u00e9server ces zones c\u00f4ti\u00e8res et marines essentielles, et le gouvernement somalien prend des mesures de protection pour aider \u00e0 atteindre cet objectif.<\/p>\n\n\n\n<p>La plateforme Digital Earth Africa permet aux chercheurs d'acc\u00e9der \u00e0 des informations g\u00e9ographiques pour \u00e9tudier les changements environnementaux. G\u00e9n\u00e9ralement, les relev\u00e9s au sol, privil\u00e9gi\u00e9s par les gestionnaires c\u00f4tiers, sont co\u00fbteux et prennent du temps. Il est n\u00e9cessaire de rechercher des m\u00e9thodes alternatives d'\u00e9valuation des \u00e9cosyst\u00e8mes pour un pays tel que la Somalie. Alternativement, l'imagerie satellitaire a \u00e9t\u00e9 utilis\u00e9e pour cartographier de telles zones, offrant un moyen rentable et un rapport opportun de cartographie des mangroves au fil du temps. Les d\u00e9veloppements dans les infrastructures publiques, tels que Digital Earth Africa (DE Africa), fournissent des donn\u00e9es pr\u00eates \u00e0 l'analyse (ARD) couvrant plus de 35 ans de Landsat (30 m\u00e8tres) et plus de sept ans de Sentinel 2 (10 m\u00e8tres).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Champion de la Terre Num\u00e9rique Afrique \u2013 Liban Hassan<\/h3>\n\n\n\n<p>Liban Hassan de Somalie a \u00e9t\u00e9 form\u00e9 \u00e0 l'utilisation de la plateforme DE Africa dans le cadre de la formation conjointe sur&nbsp;<a href=\"https:\/\/www.data4sdgs.org\/sites\/default\/files\/file_uploads\/Timely%20Monitoring%20of%20Environmental%20SDG%20Indicators%20in%20Somalia%20with%20Earth%20Observation%20and%20Geospatial%20Tools.pdf\" target=\"_blank\" rel=\"noopener\">Surveillance opportune des indicateurs environnementaux des ODD en Somalie gr\u00e2ce \u00e0 l'observation de la Terre et aux outils g\u00e9ospatiaux<\/a>&nbsp;par le&nbsp;&nbsp;<a href=\"http:\/\/www.data4sdgs.org\/\" target=\"_blank\" rel=\"noopener\">Partenariat mondial pour les donn\u00e9es du d\u00e9veloppement durable<\/a>&nbsp;(GPSDD), DE Afrique et&nbsp;<a href=\"https:\/\/nbs.gov.so\/\" target=\"_blank\" rel=\"noopener\">Bureau National de la Statistique de Somalie&nbsp;<\/a>(SNBS) tenue \u00e0 Mogadiscio, en Somalie, en f\u00e9vrier 2023. De plus, Liban utilise d\u00e9sormais les donn\u00e9es satellitaires d'analyse pr\u00eates \u00e0 l'emploi de DE Africa pour produire une s\u00e9rie chronologique destin\u00e9e \u00e0 l'analyse afin d'\u00e9tudier les mangroves en Somalie, notamment \u00e0 Berbera, Alula (Caluula en langue somalie), Kismayo, Habo (Xabo en somali) et Zeila (Zeylac en somali), afin d'\u00e9clairer les plans de r\u00e9silience et de protection des mangroves en Somalie.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">R\u00e9sultats de l'analyse des mangroves<\/h3>\n\n\n\n<p>L'analyse de DE Africa se compare \u00e0 la&nbsp;<a href=\"https:\/\/www.globalmangrovewatch.org\/\" target=\"_blank\" rel=\"noopener\">Surveillance Mondiale des Mangroves<\/a>&nbsp;(GMW), une initiative qui suit l'\u00e9tendue mondiale des mangroves. De plus, Liban a pu identifier des points chauds de 2014 \u00e0 2020 car DE Africa classe les mangroves \u00e0 l'aide de l'indice de v\u00e9g\u00e9tation par diff\u00e9rence normalis\u00e9e (NDVI) et de l'indice d'eau par diff\u00e9rence normalis\u00e9e (NDWI) et montre l'\u00e9tendue de la couverture des mangroves en vert. Cette analyse peut mettre en \u00e9vidence les zones sujettes aux catastrophes telles que les inondations ou celles qui ont subi une surexploitation des ressources en mangroves en raison de la production de sel et du bois pour le feu et le logement.<\/p>\n\n\n\n<p>Dans les cinq villes : Berbera, Alula (Caluula en langue somalie), Kismayo, Habo (Xabo en somali) et Zeila (Zeylac en somali), Liban a pu mettre en \u00e9vidence les changements dans les zones de mangrove sur la p\u00e9riode d'analyse de 2010 \u00e0 2017. Les r\u00e9sultats montrent les diff\u00e9rences dans les mangroves comme indiqu\u00e9 ci-dessous, avec la perte de mangroves repr\u00e9sent\u00e9e en rouge se produisant dans toutes les villes de Zeila, Berbera, Alula, Kismayo et Habo, et plus d'\u00e9checs apparents \u00e0 Zeila, Alula et Habo, indiquant des zones qui ont connu beaucoup d'\u00e9rosion c\u00f4ti\u00e8re. N\u00e9anmoins, de nouvelles mangroves sont observ\u00e9es \u00e0 la m\u00eame p\u00e9riode (repr\u00e9sent\u00e9es en vert) \u00e0 Alula et Xabo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"620\" src=\"https:\/\/digitalearthafrica.org\/wp-content\/uploads\/Picture-2.png\" alt=\"\" class=\"wp-image-3565\"\/><figcaption class=\"wp-element-caption\"><em>Figure 2<\/em><\/figcaption><\/figure>\n\n\n\n<p>De m\u00eame, en comparant la p\u00e9riode 2017-2022, les r\u00e9sultats indiquent que Zeila a perdu la plupart de ses mangroves (la perte de mangroves est repr\u00e9sent\u00e9e en rouge dans le diagramme ci-dessous) et que des mangroves ont \u00e9t\u00e9 restaur\u00e9es (les nouvelles mangroves sont repr\u00e9sent\u00e9es en vert) \u00e0 Xabo (Habo).<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"578\" height=\"650\" src=\"https:\/\/digitalearthafrica.org\/wp-content\/uploads\/Picture-3.png\" alt=\"\" class=\"wp-image-3564\"\/><figcaption class=\"wp-element-caption\"><em>Figure 3<\/em><\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"579\" height=\"403\" src=\"https:\/\/digitalearthafrica.org\/wp-content\/uploads\/Picture-4.png\" alt=\"\" class=\"wp-image-3563\"\/><figcaption class=\"wp-element-caption\"><em>Figure 4<\/em><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Surveillance du littoral<\/h3>\n\n\n\n<p>Liban a explor\u00e9 le service de surveillance des c\u00f4tes de DE Africa sur la Somalie pour am\u00e9liorer davantage son analyse. Les c\u00f4tes de DE Africa sont un ensemble de donn\u00e9es continentales qui comprend les lignes de rivage annuelles et les taux de changement c\u00f4tiers le long de toute la c\u00f4te africaine de 2000 \u00e0 2021 et montre des tendances permettant d'examiner chaque ann\u00e9e l'\u00e9rosion et la croissance c\u00f4ti\u00e8res. Liban a pu d\u00e9couvrir des zones sensibles, qui correspondent \u00e0 l'analyse des mangroves comme montr\u00e9 sur le service des c\u00f4tes des cartes DE Africa, en particulier \u00e0 Zeila (avec certaines zones de changement de plus de 5 m\u00e8tres de ligne de rivage) ; veuillez consulter la carte narrative.&nbsp;<a href=\"https:\/\/maps.digitalearth.africa\/#share=s-yBrFOuxlPb8JQVY20S5qoFBrtpb\" target=\"_blank\" rel=\"noopener\">https:\/\/maps.digitalearth.africa\/#share=s-yBrFOuxlPb8JQVY20S5qoFBrtpb<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"483\" src=\"https:\/\/digitalearthafrica.org\/wp-content\/uploads\/Picture-5.png\" alt=\"\" class=\"wp-image-3562\"\/><figcaption class=\"wp-element-caption\"><em>Figure 5<\/em><\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Conclusion<\/h3>\n\n\n\n<p>En conclusion, le suivi en temps opportun des mangroves en Somalie gr\u00e2ce \u00e0 la technologie avanc\u00e9e et \u00e0 la plateforme Digital Earth Africa a fourni des informations pr\u00e9cieuses sur l'\u00e9tat de ces \u00e9cosyst\u00e8mes critiques. Les mangroves, essentielles \u00e0 la r\u00e9duction de l'\u00e9rosion c\u00f4ti\u00e8re et \u00e0 la conservation de la biodiversit\u00e9, ont \u00e9t\u00e9 confront\u00e9es \u00e0 des d\u00e9fis importants en raison du changement climatique et des activit\u00e9s humaines.<\/p>\n\n\n\n<p>Cette analyse a suivi les \u00e9volutions de la couverture des mangroves au fil du temps gr\u00e2ce aux efforts d\u00e9vou\u00e9s de personnes comme Liban Hassan, qui a utilis\u00e9 les donn\u00e9es satellitaires pr\u00eates \u00e0 l'emploi de DE Africa. Les r\u00e9sultats mettent en \u00e9vidence \u00e0 la fois les zones pr\u00e9occupantes, o\u00f9 les mangroves ont \u00e9t\u00e9 perdues, et les zones d'espoir, o\u00f9 les efforts de restauration ont eu un impact positif, en particulier \u00e0 Xabo.<\/p>\n\n\n\n<p>De plus, l'exploration par Liban du service DE Africa Coastline Monitoring a r\u00e9v\u00e9l\u00e9 des corr\u00e9lations entre l'analyse des mangroves et les changements c\u00f4tiers, soulignant ainsi l'importance de pr\u00e9server ces habitats vitaux. La technologie et les outils g\u00e9ospatiaux nous ont permis de mieux comprendre et de relever les d\u00e9fis auxquels sont confront\u00e9es les mangroves somaliennes.<\/p>\n\n\n\n<p>Dans la poursuite de l'objectif de d\u00e9veloppement durable de l'ONU 14.5, qui vise \u00e0 conserver les zones c\u00f4ti\u00e8res et marines, le travail men\u00e9 par Liban Hassan et l'int\u00e9gration des ressources de DE Africa sont des \u00e9tapes vers un avenir plus durable pour les \u00e9cosyst\u00e8mes c\u00f4tiers de la Somalie. Par des recherches, des analyses et des efforts de conservation continus, nous pouvons nous efforcer de prot\u00e9ger ces habitats essentiels et d'assurer un avenir meilleur pour notre environnement.<\/p>\n\n\n\n<p>Pour en savoir plus sur Liban Hassan Mohamed, suivez ce lien vers une courte biographie et des informations sur son parcours.<\/p>\n\n\n\n<p>Souhaitez-vous \u00eatre pr\u00e9sent\u00e9 en tant que champion de l'Afrique de la D\u00e9cennie Num\u00e9rique ?&nbsp;<a href=\"https:\/\/forms.gle\/4CK5MJ6k2PKc3UVs5\" target=\"_blank\" rel=\"noopener\">Soumettez un cas d'utilisation \u00e0 l'\u00e9quipe DE Africa.<\/a><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">NOUS CONNECTER<\/h4>\n\n\n\n<p>Site Web :&nbsp;<a href=\"https:\/\/www.digitalearthafrica.org\/\">https:\/\/www.digitalearthafrica.org<\/a>&nbsp;<\/p>\n\n\n\n<p>E-mail :&nbsp;<a href=\"mailto:info@digitalearthafrica.org\">info@digitalearthafrica.org<\/a>&nbsp;<\/p>\n\n\n\n<p>Inscrivez-vous \u00e0 nos cours d'apprentissage gratuits :&nbsp;<a href=\"https:\/\/learn.digitalearthafrica.org\/\">https:\/\/learn.digitalearthafrica.org<\/a>.<\/p>\n\n\n\n<p>Suivez-nous sur les r\u00e9seaux sociaux :<a href=\"https:\/\/twitter.com\/DEarthAfrica\" target=\"_blank\" rel=\"noopener\">&nbsp;Terre Num\u00e9rique Afrique (@DEarthAfrica)<\/a>&nbsp;sur Twitter et&nbsp;<a href=\"https:\/\/www.linkedin.com\/company\/digitalearthafrica\" target=\"_blank\" rel=\"noopener\">Terre Num\u00e9rique Afrique | LinkedIn<\/a>&nbsp;via LinkedIn.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">R\u00e9f\u00e9rences<\/h3>\n\n\n\n<p>UNEP, 2005a, Regards sur l'environnement dans les Cara\u00efbes. UNEP, Nairobi, Kenya Arthurton R, Korateng K 2000. Environnements c\u00f4tiers et marins. \u00c9TAT DE L'ENVIRONNEMENT ET TENDANCES : RETROSPECTIVE SUR 20 ANS. NOAA UNEP\/GPA 2003. Examen des l\u00e9gislations nationales relatives \u00e0 la gestion des zones c\u00f4ti\u00e8res dans les Cara\u00efbes anglophones. WIOMSA 2005. Comprendre les changements socio-\u00e9conomiques dans les communaut\u00e9s c\u00f4ti\u00e8res. Nouveau r\u00e9seau de surveillance socio-\u00e9conomique dans l'oc\u00e9an Indien occidental. WIOMSA News brief. UNEP 2006. Regards sur l'environnement en Afrique 2. Programme des Nations unies pour l'environnement, Nairobi Kenya. DAVID Obura D et Abdulla A, 2004. \u00c9valuation des impacts du tsunami sur l'environnement marin des Seychelles. CORDIO East Africa, P.O.BOX 10135, Mombasa 80101, Kenya et IUCN Global Marine Programme, Parque Tecnologico de Andalucia, Calle Marie Curie, 35, Malaga Espagne<\/p>\n\n\n\n<p>Mumuli, S. O, Alim, M. et Oduori, G., 2010. Surveillance des mangroves en Somalie (Puntland, Somaliland et Somalie centre-sud). FAO-SWALIM. Rapport de projet n\u00b0 L-19. Nairobi, Kenya<\/p>","protected":false},"excerpt":{"rendered":"<p>Mangroves in Somalia play a vital role in reducing shoreline erosion, and habitats for fish and birds are critical for conserving biological diversity. Somalia has the longest coastline of mainland African countries, approximately 3500 km, with mangrove forests found in some areas along the coast, in the northern and southwestern coastal lines, including the southern [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3561,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,12],"tags":[],"audience":[],"class_list":["post-3560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coastlines","category-use-cases"],"acf":[],"_links":{"self":[{"href":"https:\/\/digitalearthafrica.org\/fr\/wp-json\/wp\/v2\/posts\/3560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digitalearthafrica.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/digitalearthafrica.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/digitalearthafrica.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/digitalearthafrica.org\/fr\/wp-json\/wp\/v2\/comments?post=3560"}],"version-history":[{"count":2,"href":"https:\/\/digitalearthafrica.org\/fr\/wp-json\/wp\/v2\/posts\/3560\/revisions"}],"predecessor-version":[{"id":4524,"href":"https:\/\/digitalearthafrica.org\/fr\/wp-json\/wp\/v2\/posts\/3560\/revisions\/4524"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/digitalearthafrica.org\/fr\/wp-json\/wp\/v2\/media\/3561"}],"wp:attachment":[{"href":"https:\/\/digitalearthafrica.org\/fr\/wp-json\/wp\/v2\/media?parent=3560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/digitalearthafrica.org\/fr\/wp-json\/wp\/v2\/categories?post=3560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/digitalearthafrica.org\/fr\/wp-json\/wp\/v2\/tags?post=3560"},{"taxonomy":"audience","embeddable":true,"href":"https:\/\/digitalearthafrica.org\/fr\/wp-json\/wp\/v2\/audience?post=3560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}